{"id":161,"date":"2023-01-03T10:18:47","date_gmt":"2023-01-03T13:18:47","guid":{"rendered":"https:\/\/mobilesentrix.com.ar\/?post_type=product&#038;p=161"},"modified":"2026-05-04T03:09:47","modified_gmt":"2026-05-04T06:09:47","slug":"bateria-compatible-con-iphone-se-2020-2022-ampsentrix","status":"publish","type":"product","link":"https:\/\/mobilesentrix.com.ar\/index.php\/product\/bateria-compatible-con-iphone-se-2020-2022-ampsentrix\/","title":{"rendered":"Bater\u00eda compatible con iPhone SE (2020) (AMPSENTRIX)"},"content":{"rendered":"<p><span data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Bater\u00eda de repuesto de primera calidad para iPhone SE.nReemplace la bater\u00eda vieja y da\u00f1ada por el agua del iPhone SE con la marca One.nLa bater\u00eda que proporcionamos es recargable y respetuosa con el medio ambiente.nMuy recomendable la instalaci\u00f3n profesional.nDise\u00f1o especial Bater\u00eda de alta calidad para iPhone SE.nCapacidad de 1821 mAh.nCompatible con A2296 \/ A2275 \/ A2298.&quot;}\" data-sheets-userformat=\"{&quot;2&quot;:13309,&quot;3&quot;:{&quot;1&quot;:0},&quot;5&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:{&quot;1&quot;:2,&quot;2&quot;:0}},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;6&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:{&quot;1&quot;:2,&quot;2&quot;:0}},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;7&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:{&quot;1&quot;:2,&quot;2&quot;:0}},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;8&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:{&quot;1&quot;:2,&quot;2&quot;:0}},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;9&quot;:0,&quot;10&quot;:1,&quot;11&quot;:4,&quot;12&quot;:0,&quot;15&quot;:&quot;Montserrat&quot;,&quot;16&quot;:11}\" data-sheets-textstyleruns=\"{&quot;1&quot;:0}\uee10{&quot;1&quot;:354,&quot;2&quot;:{&quot;5&quot;:1}}\uee10{&quot;1&quot;:375}\">Bater\u00eda de repuesto de primera calidad para iPhone SE.<br \/>\nReemplace la bater\u00eda vieja y da\u00f1ada por el agua del iPhone SE con la marca One.<br \/>\nLa bater\u00eda que proporcionamos es recargable y respetuosa con el medio ambiente.<br \/>\nMuy recomendable la instalaci\u00f3n profesional.<br \/>\nDise\u00f1o especial Bater\u00eda de alta calidad para iPhone SE.<br \/>\nCapacidad de 1821 mAh.<br \/>\nCompatible con A2296 \/ A2275 \/ A2298.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p><span data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Bater\u00eda de repuesto de primera calidad para iPhone SE.nReemplace la bater\u00eda vieja y da\u00f1ada por el agua del iPhone SE con la marca One.nLa bater\u00eda que proporcionamos es recargable y respetuosa con el medio ambiente.nMuy recomendable la instalaci\u00f3n profesional.nDise\u00f1o especial Bater\u00eda de alta calidad para iPhone SE.nCapacidad de 1821 mAh.nCompatible con A2296 \/ A2275 \/ A2298.&quot;}\" data-sheets-userformat=\"{&quot;2&quot;:13309,&quot;3&quot;:{&quot;1&quot;:0},&quot;5&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:{&quot;1&quot;:2,&quot;2&quot;:0}},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;6&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:{&quot;1&quot;:2,&quot;2&quot;:0}},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;7&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:{&quot;1&quot;:2,&quot;2&quot;:0}},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;8&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:{&quot;1&quot;:2,&quot;2&quot;:0}},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;9&quot;:0,&quot;10&quot;:1,&quot;11&quot;:4,&quot;12&quot;:0,&quot;15&quot;:&quot;Montserrat&quot;,&quot;16&quot;:11}\" data-sheets-textstyleruns=\"{&quot;1&quot;:0}\uee10{&quot;1&quot;:354,&quot;2&quot;:{&quot;5&quot;:1}}\uee10{&quot;1&quot;:375}\">Bater\u00eda de repuesto de primera calidad para iPhone SE.<br \/>\nReemplace la bater\u00eda vieja y da\u00f1ada por el agua del iPhone SE con la marca One.<br \/>\nLa bater\u00eda que proporcionamos es recargable y respetuosa con el medio ambiente.<br \/>\nMuy recomendable la instalaci\u00f3n profesional.<br \/>\nDise\u00f1o especial Bater\u00eda de alta calidad para iPhone SE.<br \/>\nCapacidad de 1821 mAh.<br \/>\nCompatible con A2296 \/ A2275 \/ A2298.<\/span><\/p>\n","protected":false},"featured_media":664,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_cat":[24],"product_tag":[],"_links":{"self":[{"href":"https:\/\/mobilesentrix.com.ar\/index.php\/wp-json\/wp\/v2\/product\/161"}],"collection":[{"href":"https:\/\/mobilesentrix.com.ar\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mobilesentrix.com.ar\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/mobilesentrix.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=161"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mobilesentrix.com.ar\/index.php\/wp-json\/wp\/v2\/media\/664"}],"wp:attachment":[{"href":"https:\/\/mobilesentrix.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=161"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mobilesentrix.com.ar\/index.php\/wp-json\/wp\/v2\/product_cat?post=161"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mobilesentrix.com.ar\/index.php\/wp-json\/wp\/v2\/product_tag?post=161"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}